{"id":1971,"date":"2022-08-22T08:00:59","date_gmt":"2022-08-22T06:00:59","guid":{"rendered":"https:\/\/www.diagnostico-mente.org\/blog\/?p=1971"},"modified":"2022-07-12T17:04:24","modified_gmt":"2022-07-12T15:04:24","slug":"que-es-el-tdah-de-tipo-inatento","status":"publish","type":"post","link":"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/que-es-el-tdah-de-tipo-inatento\/","title":{"rendered":"\u00bfQu\u00e9 es el TDAH de tipo inatento?"},"content":{"rendered":"<h4>\u00bfQu\u00e9 es el TDAH de tipo inatento?<\/h4>\n<p>El trastorno por d\u00e9ficit de atenci\u00f3n e hiperactividad (<strong>TDAH<\/strong>) es un trastorno del neurodesarrollo que afecta al desarrollo del cerebro y a su capacidad de funcionamiento. Se calcula que el 5% de las personas de todo el mundo padecen este trastorno, que comienza en la infancia pero a menudo persiste en la edad adulta.<\/p>\n<p>El TDAH se caracteriza por dos tipos de s\u00edntomas:<\/p>\n<ul>\n<li>S\u00edntomas de falta de atenci\u00f3n: Estos s\u00edntomas pueden dificultar que la persona preste atenci\u00f3n o se mantenga organizada.<\/li>\n<li>S\u00edntomas de hiperactividad e impulsividad: Estos s\u00edntomas pueden dificultar que la persona se quede quieta, haciendo que se mueva constantemente. Pueden tener dificultades para controlar sus impulsos y su comportamiento.<\/li>\n<\/ul>\n<p>Existen tres tipos de TDAH, que se distinguen en funci\u00f3n de los s\u00edntomas que presenta la persona:<\/p>\n<ul>\n<li><a href=\"https:\/\/www.diagnostico-mente.org\/prueba-de-tdah\">TDAH de tipo<\/a> inatento: Este tipo de TDAH se caracteriza por s\u00edntomas de inatenci\u00f3n. Las personas con este tipo de TDAH pueden tener pocos o ning\u00fan s\u00edntoma de hiperactividad e impulsividad. Esta forma de TDAH se denomina a veces trastorno por d\u00e9ficit de atenci\u00f3n (TDA), aunque el t\u00e9rmino TDA est\u00e1 anticuado y ya no se utiliza.<\/li>\n<li>TDAH de tipo hiperactivo\/impulsivo: Este tipo de TDAH se caracteriza por s\u00edntomas de hiperactividad e impulsividad. Las personas con este tipo de TDAH pueden tener pocos o ning\u00fan s\u00edntoma de falta de atenci\u00f3n.<\/li>\n<li>TDAH de tipo combinado: Las personas que tienen TDAH de tipo combinado presentan s\u00edntomas de falta de atenci\u00f3n, as\u00ed como s\u00edntomas de hiperactividad e impulsividad. Este es el tipo m\u00e1s com\u00fan de TDAH.<\/li>\n<\/ul>\n<p>Hasta el 30% de las personas con TDAH tienen un TDAH de tipo inatento. Un estudio de 2014 se\u00f1al\u00f3 que el TDAH de tipo inatento es m\u00e1s sutil que otros tipos de TDAH, por lo que puede ser m\u00e1s dif\u00edcil de detectar. Por ejemplo, los alumnos con este tipo de TDAH pueden ser menos disruptivos en el aula que los ni\u00f1os que tambi\u00e9n tienen s\u00edntomas de hiperactividad e impulsividad.<\/p>\n<p>Este art\u00edculo explora los s\u00edntomas, las causas, el diagn\u00f3stico y el tratamiento del TDAH de tipo inatento.<\/p>\n<h4>S\u00edntomas del TDAH de tipo inatento<\/h4>\n<p>Los ni\u00f1os o adultos con TDAH de tipo inatento muestran principalmente s\u00edntomas de inatenci\u00f3n, que incluyen:<\/p>\n<ul>\n<li>Dificultad para concentrarse en las tareas de la escuela o el trabajo<\/li>\n<li>No prestar atenci\u00f3n a los detalles, lo que puede dar lugar a errores por descuido en el trabajo o las tareas escolares<\/li>\n<li>Desorganizaci\u00f3n, lo que hace que no se cumplan los plazos y las citas.<\/li>\n<li>Distraerse f\u00e1cilmente<\/li>\n<li>Dejar tareas incompletas, como trabajos, tareas dom\u00e9sticas u otras actividades<\/li>\n<li>Perder con frecuencia objetos personales y de valor<\/li>\n<li>Olvido frecuente de cosas<\/li>\n<li>No seguir las instrucciones y no escuchar cuando se le habla directamente<\/li>\n<li>Evitar las tareas que requieren atenci\u00f3n durante largos per\u00edodos de tiempo<\/li>\n<\/ul>\n<p style=\"padding-left: 40px;\">Los ni\u00f1os y adolescentes menores de 17 a\u00f1os deben presentar al menos seis de estos s\u00edntomas para que se les diagnostique un TDAH de tipo inatento. Los mayores de 17 a\u00f1os deben tener al menos cinco de estos s\u00edntomas.<\/p>\n<p>Adem\u00e1s de los s\u00edntomas de falta de atenci\u00f3n, las personas con TDAH de tipo inatento tambi\u00e9n pueden tener varios s\u00edntomas de hiperactividad e impulsividad, que incluyen:<\/p>\n<ul>\n<li>Mover el cuerpo, dar golpecitos o retorcerse mientras se est\u00e1 sentado<\/li>\n<li>Dificultad para permanecer sentado, por ejemplo en clase o en el trabajo<\/li>\n<li>Caminar y, en los ni\u00f1os, correr o trepar en lugar de estar sentados<\/li>\n<li>Hacer mucho ruido al jugar o participar en actividades recreativas<\/li>\n<li>Sensaci\u00f3n constante de inquietud y de estar en movimiento, como si fuera impulsado por un motor<\/li>\n<li>Hablar demasiado<\/li>\n<li>Responder a las preguntas antes de que se formulen, hablar sin sentido o terminar las frases de los dem\u00e1s<\/li>\n<li>Incapacidad de esperar pacientemente su turno<\/li>\n<li>Interrumpir, perturbar o apropiarse de las conversaciones o actividades de otras personas<\/li>\n<\/ul>\n<h4>Causas del TDAH inatento<\/h4>\n<p style=\"padding-left: 40px;\">El TDAH se caracteriza por unos niveles bajos de dopamina en el cerebro, as\u00ed como por unos niveles m\u00e1s bajos de metabolismo en las zonas del cerebro responsables de la atenci\u00f3n, el control de los impulsos y el movimiento.<\/p>\n<p>No se conocen las causas exactas de estas diferencias cerebrales; sin embargo, estos son algunos de los factores que pueden contribuir al desarrollo de esta condici\u00f3n:<\/p>\n<ul>\n<li>Factores gen\u00e9ticos: el TDAH puede heredarse gen\u00e9ticamente; un ni\u00f1o puede tener m\u00e1s riesgo de desarrollarlo si uno de sus padres o familiares lo padece.<\/li>\n<li>Factores ambientales: la exposici\u00f3n a toxinas ambientales puede desempe\u00f1ar un papel en el desarrollo del TDAH. Por ejemplo, un estudio de 2016 descubri\u00f3 que la exposici\u00f3n al plomo puede causar TDAH en los ni\u00f1os.<\/li>\n<li>Factores de las primeras etapas de la vida: el nacimiento prematuro, el consumo de alcohol o tabaco durante el embarazo y los acontecimientos traum\u00e1ticos o el trauma en las primeras etapas de la vida pueden contribuir al desarrollo del TDAH.<\/li>\n<\/ul>\n<h4>Diagn\u00f3stico del TDAH de tipo inatento<\/h4>\n<p>El TDAH de tipo inatento puede ser diagnosticado por un psiquiatra o un psic\u00f3logo. Un m\u00e9dico de atenci\u00f3n primaria, un m\u00e9dico de familia o un pediatra pueden proporcionar una referencia a un profesional sanitario especializado en el TDAH.<\/p>\n<p>El proceso de diagn\u00f3stico puede incluir:<\/p>\n<ul>\n<li>Un historial m\u00e9dico personal y familiar detallado<\/li>\n<li>Una escala de valoraci\u00f3n estandarizada o una lista de comprobaci\u00f3n de los s\u00edntomas y su gravedad<\/li>\n<li>Una entrevista con un profesional sanitario<\/li>\n<li>Entrevistas con los familiares o profesores del ni\u00f1o<\/li>\n<li>Otras pruebas psicol\u00f3gicas, an\u00e1lisis de sangre, ex\u00e1menes f\u00edsicos o estudios de imagen necesarios para descartar otras trastornoes o confirmar el diagn\u00f3stico.<\/li>\n<\/ul>\n<p>El m\u00e9dico determinar\u00e1 si los s\u00edntomas de la persona cumplen los criterios diagn\u00f3sticos del TDAH de tipo inatento establecidos en el Manual de Diagn\u00f3stico y Estad\u00edstica de la Asociaci\u00f3n Americana de Psiquiatr\u00eda:<\/p>\n<ul>\n<li>La persona ha tenido s\u00edntomas durante m\u00e1s de seis meses.<\/li>\n<li>La persona ha tenido m\u00faltiples s\u00edntomas desde antes de los 12 a\u00f1os.<\/li>\n<li>Los s\u00edntomas se producen en dos o m\u00e1s entornos, como la escuela\/el trabajo, el hogar, los entornos sociales o mientras se realizan otras actividades.<\/li>\n<li>Los s\u00edntomas interfieren significativamente en la capacidad de funcionamiento de la persona.<\/li>\n<li>Los s\u00edntomas no se explican mejor por otra condici\u00f3n de salud mental.<\/li>\n<\/ul>\n<p>Es importante recordar que los s\u00edntomas del TDAH de una persona pueden cambiar con el tiempo a medida que envejece. Por lo tanto, el tipo de TDAH que tienen tambi\u00e9n puede cambiar. Por lo tanto, aunque actualmente tengan un TDAH de tipo inatento, esto puede cambiar en el futuro.<\/p>\n<h4>Tratamiento del TDAH de tipo inatento<\/h4>\n<p>El tratamiento puede ayudar a las personas con TDAH de tipo inatento a controlar sus s\u00edntomas y a reducir las dificultades, especialmente las relacionadas con el trabajo o la escuela, donde se requiere concentraci\u00f3n. Las opciones de tratamiento incluyen la medicaci\u00f3n y la terapia.<\/p>\n<h4>Medicamentos<\/h4>\n<p>Hay varios medicamentos aprobados por la FDA que pueden tratar a personas de seis a\u00f1os o m\u00e1s. Estos son algunos de los tipos de medicamentos que pueden recetarse para tratar el TDAH inatento:<\/p>\n<ul>\n<li>Estimulantes: Estos son los medicamentos m\u00e1s utilizados para tratar el TDAH. Los estimulantes act\u00faan aumentando los niveles de las sustancias qu\u00edmicas dopamina y norepinefrina en el cerebro para ayudar a la atenci\u00f3n y la cognici\u00f3n.<\/li>\n<li>No estimulantes: Estos f\u00e1rmacos tardan m\u00e1s en hacer efecto que los estimulantes, pero tambi\u00e9n pueden ayudar con los s\u00edntomas del TDAH de tipo inatento. Los no estimulantes pueden recetarse en combinaci\u00f3n con los estimulantes si \u00e9stos son ineficaces o si los estimulantes provocan demasiados efectos secundarios.<\/li>\n<li>Antidepresivos: Dependiendo de los s\u00edntomas de la persona, de los efectos secundarios y de cualquier otra condici\u00f3n de salud que pueda tener, su proveedor de atenci\u00f3n m\u00e9dica tambi\u00e9n puede prescribir antidepresivos. Los antidepresivos pueden ser especialmente \u00fatiles si la persona tiene tambi\u00e9n un trastorno del estado de \u00e1nimo o de ansiedad.<\/li>\n<\/ul>\n<h4>Terapia<\/h4>\n<p>La terapia puede ayudar a las personas con TDAH de tipo inatento a mejorar su concentraci\u00f3n y a gestionar mejor su condici\u00f3n. Estas son algunas formas de terapia que pueden ser \u00fatiles:<\/p>\n<ul>\n<li>La terapia conductual, que ayuda a las personas a controlar y cambiar su comportamiento.<\/li>\n<li>La terapia cognitivo-conductual, que ayuda a las personas a ser m\u00e1s conscientes de sus procesos de pensamiento y les ense\u00f1a a mejorar su enfoque y concentraci\u00f3n.<\/li>\n<li>Terapia familiar y marital, que ayuda a las parejas y a los miembros de la familia a aprender a apoyar a la persona con TDAH de tipo inatento y a mejorar sus interacciones con ella.<\/li>\n<li>Entrenamiento en habilidades parentales, que tambi\u00e9n se conoce como entrenamiento conductual para padres. Puede ense\u00f1ar a los padres cuyos hijos tienen TDAH c\u00f3mo fomentar el comportamiento positivo de sus hijos y desalentar el comportamiento negativo.<\/li>\n<li>Grupos de apoyo que pueden ayudar a las personas con TDAH y a sus padres o familias a ponerse en contacto con otras personas que comparten sus experiencias.<\/li>\n<\/ul>\n<h4>C\u00f3mo afrontar el TDAH de tipo inatento<\/h4>\n<p>A continuaci\u00f3n se exponen algunas medidas que pueden ayudar a las personas con TDAH de tipo inatento a enfrentarse a la trastorno:<\/p>\n<ul>\n<li>Limite las distracciones: Apagar el televisor, mantener un espacio de trabajo limpio y limitar otros ruidos y distracciones cuando se intenta trabajar para ayudar a mejorar la concentraci\u00f3n.<\/li>\n<li>Separe las tareas largas: Las tareas que requieren una atenci\u00f3n sostenida pueden ser desalentadoras para las personas con TDAH de tipo inatento. Dividir una tarea en trozos m\u00e1s peque\u00f1os puede hacerla m\u00e1s manejable.<\/li>\n<li>Presupuestar el tiempo suficiente: Puede ser \u00fatil empezar a trabajar en las tareas escolares o en los trabajos con antelaci\u00f3n, planificando bastantes descansos para las actividades entre ellas.<\/li>\n<li>Construye una rutina: Puede ser \u00fatil crear y mantener una rutina diaria para fomentar la constancia.<\/li>\n<li>Lleve un estilo de vida saludable: siga una dieta nutritiva, duerma lo suficiente y haga ejercicio regularmente.<\/li>\n<\/ul>\n<h4>Leer m\u00e1s<\/h4>\n<ul>\n<li><em>verywellmind.com\/adhd-inattentive-type-symptoms-diagnosis-and-treatment-5224357<\/em><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfQu\u00e9 es el TDAH de tipo inatento? El trastorno por d\u00e9ficit de atenci\u00f3n e hiperactividad (TDAH) es un trastorno del neurodesarrollo que afecta al desarrollo&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1718,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false},"categories":[37],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfQu\u00e9 es el TDAH de tipo inatento? - Diagn\u00f3stico Mente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/que-es-el-tdah-de-tipo-inatento\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 es el TDAH de tipo inatento? - Diagn\u00f3stico Mente\" \/>\n<meta property=\"og:description\" content=\"\u00bfQu\u00e9 es el TDAH de tipo inatento? El trastorno por d\u00e9ficit de atenci\u00f3n e hiperactividad (TDAH) es un trastorno del neurodesarrollo que afecta al desarrollo...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/que-es-el-tdah-de-tipo-inatento\/\" \/>\n<meta property=\"og:site_name\" content=\"Diagn\u00f3stico Mente\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-22T06:00:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-12T15:04:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.diagnostico-mente.org\/blog\/wp-content\/uploads\/2022\/07\/bg_top_default-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"840\" \/>\n\t<meta property=\"og:image:height\" content=\"202\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diagn\u00f3stico Mente\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.diagnostico-mente.org\/blog\/#organization\",\"name\":\"Diagn\u00f3stico Mente\",\"url\":\"https:\/\/www.diagnostico-mente.org\/blog\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.diagnostico-mente.org\/blog\/#logo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/www.diagnostico-mente.org\/blog\/wp-content\/uploads\/2022\/06\/logo_blog.png\",\"contentUrl\":\"https:\/\/www.diagnostico-mente.org\/blog\/wp-content\/uploads\/2022\/06\/logo_blog.png\",\"width\":252,\"height\":75,\"caption\":\"Diagn\u00f3stico Mente\"},\"image\":{\"@id\":\"https:\/\/www.diagnostico-mente.org\/blog\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.diagnostico-mente.org\/blog\/#website\",\"url\":\"https:\/\/www.diagnostico-mente.org\/blog\/\",\"name\":\"Diagn\u00f3stico Mente\",\"description\":\"Blog sobre los trastornos de la mente\",\"publisher\":{\"@id\":\"https:\/\/www.diagnostico-mente.org\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.diagnostico-mente.org\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/que-es-el-tdah-de-tipo-inatento\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/www.diagnostico-mente.org\/blog\/wp-content\/uploads\/2022\/07\/bg_top_default-1.jpg\",\"contentUrl\":\"https:\/\/www.diagnostico-mente.org\/blog\/wp-content\/uploads\/2022\/07\/bg_top_default-1.jpg\",\"width\":840,\"height\":202},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/que-es-el-tdah-de-tipo-inatento\/#webpage\",\"url\":\"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/que-es-el-tdah-de-tipo-inatento\/\",\"name\":\"\u00bfQu\u00e9 es el TDAH de tipo inatento? - Diagn\u00f3stico Mente\",\"isPartOf\":{\"@id\":\"https:\/\/www.diagnostico-mente.org\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/que-es-el-tdah-de-tipo-inatento\/#primaryimage\"},\"datePublished\":\"2022-08-22T06:00:59+00:00\",\"dateModified\":\"2022-07-12T15:04:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/que-es-el-tdah-de-tipo-inatento\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/que-es-el-tdah-de-tipo-inatento\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/que-es-el-tdah-de-tipo-inatento\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"P\u00e1gina\",\"item\":\"https:\/\/www.diagnostico-mente.org\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TDAH\",\"item\":\"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00bfQu\u00e9 es el TDAH de tipo inatento?\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/que-es-el-tdah-de-tipo-inatento\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/que-es-el-tdah-de-tipo-inatento\/#webpage\"},\"author\":{\"@id\":\"https:\/\/www.diagnostico-mente.org\/blog\/#\/schema\/person\/8eb1bcaf59fea75c780c11946f4e3490\"},\"headline\":\"\u00bfQu\u00e9 es el TDAH de tipo inatento?\",\"datePublished\":\"2022-08-22T06:00:59+00:00\",\"dateModified\":\"2022-07-12T15:04:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/que-es-el-tdah-de-tipo-inatento\/#webpage\"},\"wordCount\":1741,\"publisher\":{\"@id\":\"https:\/\/www.diagnostico-mente.org\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/que-es-el-tdah-de-tipo-inatento\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.diagnostico-mente.org\/blog\/wp-content\/uploads\/2022\/07\/bg_top_default-1.jpg\",\"articleSection\":[\"TDAH\"],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.diagnostico-mente.org\/blog\/#\/schema\/person\/8eb1bcaf59fea75c780c11946f4e3490\",\"name\":\"Diagn\u00f3stico Mente\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.diagnostico-mente.org\/blog\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/db47a00a472ca08e0cb5053901a4e9b1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/db47a00a472ca08e0cb5053901a4e9b1?s=96&d=mm&r=g\",\"caption\":\"Diagn\u00f3stico Mente\"},\"sameAs\":[\"https:\/\/www.diagnostico-mente.org\/blog\"],\"url\":\"https:\/\/www.diagnostico-mente.org\/blog\/author\/diagnostyka-umyslu\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 es el TDAH de tipo inatento? - Diagn\u00f3stico Mente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/que-es-el-tdah-de-tipo-inatento\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQu\u00e9 es el TDAH de tipo inatento? - Diagn\u00f3stico Mente","og_description":"\u00bfQu\u00e9 es el TDAH de tipo inatento? El trastorno por d\u00e9ficit de atenci\u00f3n e hiperactividad (TDAH) es un trastorno del neurodesarrollo que afecta al desarrollo...","og_url":"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/que-es-el-tdah-de-tipo-inatento\/","og_site_name":"Diagn\u00f3stico Mente","article_published_time":"2022-08-22T06:00:59+00:00","article_modified_time":"2022-07-12T15:04:24+00:00","og_image":[{"width":840,"height":202,"url":"https:\/\/www.diagnostico-mente.org\/blog\/wp-content\/uploads\/2022\/07\/bg_top_default-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Diagn\u00f3stico Mente","Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/www.diagnostico-mente.org\/blog\/#organization","name":"Diagn\u00f3stico Mente","url":"https:\/\/www.diagnostico-mente.org\/blog\/","sameAs":[],"logo":{"@type":"ImageObject","@id":"https:\/\/www.diagnostico-mente.org\/blog\/#logo","inLanguage":"es","url":"https:\/\/www.diagnostico-mente.org\/blog\/wp-content\/uploads\/2022\/06\/logo_blog.png","contentUrl":"https:\/\/www.diagnostico-mente.org\/blog\/wp-content\/uploads\/2022\/06\/logo_blog.png","width":252,"height":75,"caption":"Diagn\u00f3stico Mente"},"image":{"@id":"https:\/\/www.diagnostico-mente.org\/blog\/#logo"}},{"@type":"WebSite","@id":"https:\/\/www.diagnostico-mente.org\/blog\/#website","url":"https:\/\/www.diagnostico-mente.org\/blog\/","name":"Diagn\u00f3stico Mente","description":"Blog sobre los trastornos de la mente","publisher":{"@id":"https:\/\/www.diagnostico-mente.org\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.diagnostico-mente.org\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/que-es-el-tdah-de-tipo-inatento\/#primaryimage","inLanguage":"es","url":"https:\/\/www.diagnostico-mente.org\/blog\/wp-content\/uploads\/2022\/07\/bg_top_default-1.jpg","contentUrl":"https:\/\/www.diagnostico-mente.org\/blog\/wp-content\/uploads\/2022\/07\/bg_top_default-1.jpg","width":840,"height":202},{"@type":"WebPage","@id":"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/que-es-el-tdah-de-tipo-inatento\/#webpage","url":"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/que-es-el-tdah-de-tipo-inatento\/","name":"\u00bfQu\u00e9 es el TDAH de tipo inatento? - Diagn\u00f3stico Mente","isPartOf":{"@id":"https:\/\/www.diagnostico-mente.org\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/que-es-el-tdah-de-tipo-inatento\/#primaryimage"},"datePublished":"2022-08-22T06:00:59+00:00","dateModified":"2022-07-12T15:04:24+00:00","breadcrumb":{"@id":"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/que-es-el-tdah-de-tipo-inatento\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.diagnostico-mente.org\/blog\/tdah\/que-es-el-tdah-de-tipo-inatento\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/que-es-el-tdah-de-tipo-inatento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"P\u00e1gina","item":"https:\/\/www.diagnostico-mente.org\/blog\/"},{"@type":"ListItem","position":2,"name":"TDAH","item":"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/"},{"@type":"ListItem","position":3,"name":"\u00bfQu\u00e9 es el TDAH de tipo inatento?"}]},{"@type":"Article","@id":"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/que-es-el-tdah-de-tipo-inatento\/#article","isPartOf":{"@id":"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/que-es-el-tdah-de-tipo-inatento\/#webpage"},"author":{"@id":"https:\/\/www.diagnostico-mente.org\/blog\/#\/schema\/person\/8eb1bcaf59fea75c780c11946f4e3490"},"headline":"\u00bfQu\u00e9 es el TDAH de tipo inatento?","datePublished":"2022-08-22T06:00:59+00:00","dateModified":"2022-07-12T15:04:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/que-es-el-tdah-de-tipo-inatento\/#webpage"},"wordCount":1741,"publisher":{"@id":"https:\/\/www.diagnostico-mente.org\/blog\/#organization"},"image":{"@id":"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/que-es-el-tdah-de-tipo-inatento\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diagnostico-mente.org\/blog\/wp-content\/uploads\/2022\/07\/bg_top_default-1.jpg","articleSection":["TDAH"],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.diagnostico-mente.org\/blog\/#\/schema\/person\/8eb1bcaf59fea75c780c11946f4e3490","name":"Diagn\u00f3stico Mente","image":{"@type":"ImageObject","@id":"https:\/\/www.diagnostico-mente.org\/blog\/#personlogo","inLanguage":"es","url":"https:\/\/secure.gravatar.com\/avatar\/db47a00a472ca08e0cb5053901a4e9b1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/db47a00a472ca08e0cb5053901a4e9b1?s=96&d=mm&r=g","caption":"Diagn\u00f3stico Mente"},"sameAs":["https:\/\/www.diagnostico-mente.org\/blog"],"url":"https:\/\/www.diagnostico-mente.org\/blog\/author\/diagnostyka-umyslu\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.diagnostico-mente.org\/blog\/wp-json\/wp\/v2\/posts\/1971"}],"collection":[{"href":"https:\/\/www.diagnostico-mente.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diagnostico-mente.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diagnostico-mente.org\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diagnostico-mente.org\/blog\/wp-json\/wp\/v2\/comments?post=1971"}],"version-history":[{"count":1,"href":"https:\/\/www.diagnostico-mente.org\/blog\/wp-json\/wp\/v2\/posts\/1971\/revisions"}],"predecessor-version":[{"id":1973,"href":"https:\/\/www.diagnostico-mente.org\/blog\/wp-json\/wp\/v2\/posts\/1971\/revisions\/1973"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diagnostico-mente.org\/blog\/wp-json\/wp\/v2\/media\/1718"}],"wp:attachment":[{"href":"https:\/\/www.diagnostico-mente.org\/blog\/wp-json\/wp\/v2\/media?parent=1971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diagnostico-mente.org\/blog\/wp-json\/wp\/v2\/categories?post=1971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diagnostico-mente.org\/blog\/wp-json\/wp\/v2\/tags?post=1971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}