{"id":1918,"date":"2022-08-01T08:00:03","date_gmt":"2022-08-01T06:00:03","guid":{"rendered":"https:\/\/www.diagnostico-mente.org\/blog\/?p=1918"},"modified":"2022-07-11T20:37:36","modified_gmt":"2022-07-11T18:37:36","slug":"tda-y-tdah-diferencias-diagnostico-y-tratamiento","status":"publish","type":"post","link":"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/tda-y-tdah-diferencias-diagnostico-y-tratamiento\/","title":{"rendered":"TDA y TDAH: Diferencias, diagn\u00f3stico y tratamiento"},"content":{"rendered":"<p>El trastorno por d\u00e9ficit de atenci\u00f3n (TDA) es un t\u00e9rmino que a veces se utiliza para referirse a una forma de trastorno por d\u00e9ficit de atenci\u00f3n\/hiperactividad (TDAH). El TDAH es un trastorno neurol\u00f3gico que provoca una serie de problemas de comportamiento, como dificultades para seguir instrucciones, concentrarse en las tareas escolares, mantener el ritmo de las tareas, seguir instrucciones, completar tareas e interactuar socialmente.<\/p>\n<p>En el Manual diagn\u00f3stico y estad\u00edstico de los trastornos mentales, quinta edici\u00f3n (DSM-5), el trastorno se conoce oficialmente como &#8220;trastorno por d\u00e9ficit de atenci\u00f3n\/hiperactividad con predominio de d\u00e9ficit de atenci\u00f3n&#8221;.<\/p>\n<blockquote><p>Aunque el t\u00e9rmino TDA est\u00e1 t\u00e9cnicamente obsoleto -y ya no es utilizado por los profesionales de la salud-, a veces se sigue utilizando coloquialmente para referirse a alguien que tiene dificultades para mantenerse concentrado pero no experimenta s\u00edntomas de hiperactividad.<\/p><\/blockquote>\n<h4>S\u00edntomas del TDA (TDAH de tipo inatento)<\/h4>\n<p>Las personas con TDAH de tipo inatento tienen dificultades para centrar la atenci\u00f3n o mantener la concentraci\u00f3n durante largos periodos de tiempo. Algunos de los s\u00edntomas de este tipo de TDAH son<\/p>\n<ul>\n<li>Distraerse f\u00e1cilmente<\/li>\n<li>Dificultad para seguir instrucciones<\/li>\n<li>Dificultad para mantenerse en la tarea<\/li>\n<li>Olvidando<\/li>\n<li>P\u00e9rdida de objetos personales, como llaves o libros<\/li>\n<li>No prestar atenci\u00f3n a los detalles<\/li>\n<li>Problemas para organizarse<\/li>\n<li>Corta capacidad de atenci\u00f3n<\/li>\n<\/ul>\n<p>Los ni\u00f1os con TDAH sin un componente de hiperactividad pueden parecer aburridos o desinteresados en las actividades del aula. Pueden tender a so\u00f1ar despiertos u olvidar, trabajar a un ritmo lento y entregar trabajos incompletos.<\/p>\n<p>Sus tareas, escritorios y casilleros pueden parecer desorganizados. Pueden perder materiales en la escuela y en casa o extraviar las tareas escolares y no entregarlas. Esto puede frustrar a los profesores y a los padres y hace que el ni\u00f1o reciba malas notas en clase.<\/p>\n<h4>El TDA frente al TDAH: \u00bfCu\u00e1l es la diferencia?<\/h4>\n<p>Aunque mucha gente sigue utilizando los t\u00e9rminos TDA y TDAH indistintamente, es importante saber que no son lo mismo. He aqu\u00ed algunos puntos clave que hay que tener en cuenta:<\/p>\n<ul>\n<li>TDA es el t\u00e9rmino m\u00e1s antiguo para lo que ahora se conoce como el tipo inatento de TDAH.<\/li>\n<li>El t\u00e9rmino TDAH se ha utilizado para describir tanto los tipos de TDAH inatentos como los hiperactivos desde mediados de la d\u00e9cada de 1990.<\/li>\n<li>Sin embargo, algunas personas siguen utilizando el t\u00e9rmino TDA para indicar que la trastorno no incluye la hiperactividad como s\u00edntoma.<\/li>\n<li>El DSM-5 distingue actualmente tres subtipos de TDAH: el tipo inatento (a veces denominado habitualmente TDA), el tipo hiperactivo-impulsivo y el tipo mixto.<\/li>\n<\/ul>\n<p>El TDA (TDAH de tipo inatento) no se manifiesta de la misma manera que el tipo dominante hiperactivo o combinado. Los ni\u00f1os con estas variedades tienen s\u00edntomas diferentes.<\/p>\n<p>Los ni\u00f1os con los otros dos tipos de TDAH, por ejemplo, tienden a comportarse mal o a mostrar problemas de conducta en el aula. Los ni\u00f1os con TDAH de tipo inatento no suelen ser disruptivos en la escuela. Incluso pueden sentarse tranquilamente en clase, pero esto no significa que su trastorno no sea un problema y que no tengan dificultades para concentrarse. Adem\u00e1s, no todos los ni\u00f1os con TDAH de tipo inatento son iguales.<\/p>\n<p>Los ni\u00f1os con TDAH de tipo mixto presentan varios s\u00edntomas tanto del tipo hiperactivo-impulsivo como del inatento.<\/p>\n<h4>Diagn\u00f3stico<\/h4>\n<p>Merece la pena utilizar un <a href=\"https:\/\/www.diagnostico-mente.org\/prueba-de-tdah\">test para el TDAH<\/a>. Si sospecha que su hijo tiene TDAH, hable con el consejero escolar, el profesor o el m\u00e9dico sobre el tratamiento adecuado. Si tiene alguna preocupaci\u00f3n, inicie estas conversaciones hoy mismo. Una intervenci\u00f3n temprana puede hacer que su hijo tenga menos probabilidades de sufrir trastornos como consecuencia de la trastorno.<\/p>\n<p>Su pediatra puede recomendarle una visita a un psic\u00f3logo infantil, que puede realizar pruebas formales para ver si su hijo cumple los criterios del TDAH y, si es as\u00ed, en qu\u00e9 lugar del espectro se encuentra. Estas pruebas no s\u00f3lo pueden ayudar a distinguir el TDAH de otros problemas que pueden causar dificultades de aprendizaje en la escuela, sino que tambi\u00e9n pueden utilizarse para seguir la respuesta del ni\u00f1o a las intervenciones a lo largo del tiempo.<\/p>\n<blockquote><p>Dependiendo de los s\u00edntomas del ni\u00f1o, se le puede diagnosticar como inatento, impulsivo-hiperactivo o TDAH combinado.<\/p><\/blockquote>\n<h4>Tratamiento<\/h4>\n<p>No hay cura para el TDAH, pero el tratamiento puede ayudar a los ni\u00f1os a controlar los s\u00edntomas y mejorar su funcionamiento diario. El tratamiento del TDAH suele incluir medicaci\u00f3n, intervenciones conductuales o una combinaci\u00f3n de ambas. El tipo de tratamiento elegido depende de los s\u00edntomas y las necesidades del ni\u00f1o.<\/p>\n<h4>Medicaci\u00f3n<\/h4>\n<p>El TDAH suele tratarse con uno de los tres tipos de medicaci\u00f3n: psicoestimulantes, antidepresivos o medicaci\u00f3n no estimulante. Estos medicamentos pueden ayudar a los ni\u00f1os con TDAH del tipo inatento (ADD) a centrarse en las tareas y mantener la concentraci\u00f3n.<\/p>\n<ul>\n<li>Psicoestimulantes: Los psicoestimulantes afectan a los neurotransmisores del cerebro y pueden ayudar a aumentar la energ\u00eda y el estado de alerta. A menudo se recomienda una forma de liberaci\u00f3n prolongada (en lugar de una forma de liberaci\u00f3n inmediata). Los psicoestimulantes incluyen anfetaminas como Adderall y metilfenidatos como Ritalin y Concerta.<\/li>\n<li>Antidepresivos: Los antidepresivos tambi\u00e9n afectan a los neurotransmisores del cerebro y pueden ayudar a mejorar el estado de \u00e1nimo y la atenci\u00f3n. Los antidepresivos m\u00e1s populares que se recetan para la forma inatenta del TDAH son Wellbutrin (bupropi\u00f3n) y Effexor (venlafaxina).<\/li>\n<li>Medicamentos no estimulantes: Los medicamentos no estimulantes pueden ser \u00fatiles para las personas que experimentan efectos secundarios adversos de los medicamentos estimulantes e incluyen Strattera (atomoxetina), Qelbree (viloxazina) e Intuniv (guanfacina). Los f\u00e1rmacos no estimulantes afectan a un neurotransmisor espec\u00edfico, la norepinefrina, y pueden ayudar a regular las emociones y aumentar la concentraci\u00f3n en tareas espec\u00edficas.<\/li>\n<\/ul>\n<p>Como ocurre con cualquier medicamento, existen efectos secundarios comunes. Los psicoestimulantes, los antidepresivos y los no estimulantes pueden provocar mareos, p\u00e9rdida de apetito, malestar estomacal, etc. Hable con su m\u00e9dico si nota que su hijo experimenta alg\u00fan s\u00edntoma inusual.<\/p>\n<h4>Gesti\u00f3n del comportamiento<\/h4>\n<p>Tanto si los padres optan por el tratamiento farmacol\u00f3gico como si no, la mayor\u00eda de los m\u00e9dicos y psic\u00f3logos infantiles sugieren que se desarrolle un plan de intervenci\u00f3n conductual para ayudar a los ni\u00f1os a aprender habilidades adaptativas y a reducir el comportamiento desatento e incumplidor.<\/p>\n<p>A menudo se utiliza una combinaci\u00f3n de m\u00e9todos, incluyendo:<\/p>\n<ul>\n<li>Terapia conductual: En el caso de los ni\u00f1os peque\u00f1os, el terapeuta suele reunirse con los padres y el ni\u00f1o. Durante la sesi\u00f3n, el terapeuta suele facilitar una conversaci\u00f3n con el ni\u00f1o e incluso realizar ejercicios para ayudarle a expresar sus sentimientos. El m\u00e9dico o el terapeuta pueden recomendar la terapia familiar para que todos los miembros de la familia puedan aprender formas saludables de afrontar la trastorno del ni\u00f1o.<\/li>\n<li>Formaci\u00f3n en control de la conducta para padres: Recomendado para padres de ni\u00f1os menores de 12 a\u00f1os; el terapeuta formar\u00e1 a los padres para facilitar el cambio de comportamiento de su hijo. Aprender\u00e1 estrategias, como la terapia de juego y la terapia de conversaci\u00f3n, para que su hijo pueda expresar libremente sus sentimientos y le ayude a adoptar mecanismos de afrontamiento saludables para lidiar con las emociones dif\u00edciles.<\/li>\n<li>Intervenciones sobre el comportamiento en la escuela: Es posible que su hijo re\u00fana los requisitos para recibir asistencia adicional en virtud de la Ley de Educaci\u00f3n para Personas con Discapacidades (IDEA) o del art\u00edculo 504 de la Ley de Rehabilitaci\u00f3n de 1973. La ayuda puede incluir tiempo extra en los ex\u00e1menes, descansos adicionales, cambios en el entorno, refuerzos positivos y tareas dise\u00f1adas espec\u00edficamente para el ni\u00f1o.<\/li>\n<li>Intervenciones conductuales con los compa\u00f1eros: En este enfoque, un terapeuta o profesional capacitado dirige a un grupo de ni\u00f1os en actividades que les ense\u00f1an a interactuar de forma constructiva con sus compa\u00f1eros. Se ense\u00f1an habilidades como mantener una conversaci\u00f3n, lidiar con las burlas y hacer amigos. Los padres y los profesores pueden recibir formaci\u00f3n para reforzar las lecciones en casa y en la escuela.<\/li>\n<\/ul>\n<blockquote><p>Los planes de intervenci\u00f3n conductual pueden ser beneficiosos a largo plazo, ya que estas adaptaciones pueden dar lugar a mejoras duraderas en la capacidad de concentraci\u00f3n que la medicaci\u00f3n no proporciona.<\/p><\/blockquote>\n<p>Muchos creen que los m\u00e9todos hol\u00edsticos son eficaces para tratar los s\u00edntomas conductuales del TDAH en los ni\u00f1os. Se ha demostrado que el ejercicio regular mejora el estado de \u00e1nimo, la atenci\u00f3n y el funcionamiento ejecutivo en adultos y ni\u00f1os con TDAH.<\/p>\n<p>Los estudios han demostrado una mejora de la concentraci\u00f3n y la regulaci\u00f3n emocional en personas con TDAH despu\u00e9s de practicar yoga.<\/p>\n<p>La dieta tambi\u00e9n puede desempe\u00f1ar un papel en la gesti\u00f3n de los comportamientos del TDAH. Hay algunas investigaciones que indican que los alimentos fritos, los az\u00facares a\u00f1adidos, la sal y los ingredientes artificiales pueden empeorar los problemas de comportamiento y atenci\u00f3n.<\/p>\n<p>Sin embargo, se necesitan m\u00e1s investigaciones para comprender c\u00f3mo afecta la dieta al TDAH. Hable con el m\u00e9dico de su hijo para asegurarse de que est\u00e1 recibiendo una nutrici\u00f3n adecuada, comiendo comidas regulares y muchas verduras, todo lo cual se ha relacionado con la mejora del estado de \u00e1nimo en los ni\u00f1os con TDAH.<\/p>\n<h4>Leer m\u00e1s<\/h4>\n<ul>\n<li><em>verywellmind.com\/add-and-attention-deficit-disorders-2161810<\/em><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>El trastorno por d\u00e9ficit de atenci\u00f3n (TDA) es un t\u00e9rmino que a veces se utiliza para referirse a una forma de trastorno por d\u00e9ficit de&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1718,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false},"categories":[37],"tags":[917,918],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>TDA y TDAH: Diferencias, diagn\u00f3stico y tratamiento - Diagn\u00f3stico Mente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/tda-y-tdah-diferencias-diagnostico-y-tratamiento\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TDA y TDAH: Diferencias, diagn\u00f3stico y tratamiento - Diagn\u00f3stico Mente\" \/>\n<meta property=\"og:description\" content=\"El trastorno por d\u00e9ficit de atenci\u00f3n (TDA) es un t\u00e9rmino que a veces se utiliza para referirse a una forma de trastorno por d\u00e9ficit de...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/tda-y-tdah-diferencias-diagnostico-y-tratamiento\/\" \/>\n<meta property=\"og:site_name\" content=\"Diagn\u00f3stico Mente\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-01T06:00:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-11T18:37:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.diagnostico-mente.org\/blog\/wp-content\/uploads\/2022\/07\/bg_top_default-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"840\" \/>\n\t<meta property=\"og:image:height\" content=\"202\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diagn\u00f3stico Mente\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.diagnostico-mente.org\/blog\/#organization\",\"name\":\"Diagn\u00f3stico Mente\",\"url\":\"https:\/\/www.diagnostico-mente.org\/blog\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.diagnostico-mente.org\/blog\/#logo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/www.diagnostico-mente.org\/blog\/wp-content\/uploads\/2022\/06\/logo_blog.png\",\"contentUrl\":\"https:\/\/www.diagnostico-mente.org\/blog\/wp-content\/uploads\/2022\/06\/logo_blog.png\",\"width\":252,\"height\":75,\"caption\":\"Diagn\u00f3stico Mente\"},\"image\":{\"@id\":\"https:\/\/www.diagnostico-mente.org\/blog\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.diagnostico-mente.org\/blog\/#website\",\"url\":\"https:\/\/www.diagnostico-mente.org\/blog\/\",\"name\":\"Diagn\u00f3stico Mente\",\"description\":\"Blog sobre los trastornos de la mente\",\"publisher\":{\"@id\":\"https:\/\/www.diagnostico-mente.org\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.diagnostico-mente.org\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/tda-y-tdah-diferencias-diagnostico-y-tratamiento\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/www.diagnostico-mente.org\/blog\/wp-content\/uploads\/2022\/07\/bg_top_default-1.jpg\",\"contentUrl\":\"https:\/\/www.diagnostico-mente.org\/blog\/wp-content\/uploads\/2022\/07\/bg_top_default-1.jpg\",\"width\":840,\"height\":202},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/tda-y-tdah-diferencias-diagnostico-y-tratamiento\/#webpage\",\"url\":\"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/tda-y-tdah-diferencias-diagnostico-y-tratamiento\/\",\"name\":\"TDA y TDAH: Diferencias, diagn\u00f3stico y tratamiento - Diagn\u00f3stico Mente\",\"isPartOf\":{\"@id\":\"https:\/\/www.diagnostico-mente.org\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/tda-y-tdah-diferencias-diagnostico-y-tratamiento\/#primaryimage\"},\"datePublished\":\"2022-08-01T06:00:03+00:00\",\"dateModified\":\"2022-07-11T18:37:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/tda-y-tdah-diferencias-diagnostico-y-tratamiento\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/tda-y-tdah-diferencias-diagnostico-y-tratamiento\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/tda-y-tdah-diferencias-diagnostico-y-tratamiento\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"P\u00e1gina\",\"item\":\"https:\/\/www.diagnostico-mente.org\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TDAH\",\"item\":\"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"TDA y TDAH: Diferencias, diagn\u00f3stico y tratamiento\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/tda-y-tdah-diferencias-diagnostico-y-tratamiento\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/tda-y-tdah-diferencias-diagnostico-y-tratamiento\/#webpage\"},\"author\":{\"@id\":\"https:\/\/www.diagnostico-mente.org\/blog\/#\/schema\/person\/8eb1bcaf59fea75c780c11946f4e3490\"},\"headline\":\"TDA y TDAH: Diferencias, diagn\u00f3stico y tratamiento\",\"datePublished\":\"2022-08-01T06:00:03+00:00\",\"dateModified\":\"2022-07-11T18:37:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/tda-y-tdah-diferencias-diagnostico-y-tratamiento\/#webpage\"},\"wordCount\":1626,\"publisher\":{\"@id\":\"https:\/\/www.diagnostico-mente.org\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/tda-y-tdah-diferencias-diagnostico-y-tratamiento\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.diagnostico-mente.org\/blog\/wp-content\/uploads\/2022\/07\/bg_top_default-1.jpg\",\"keywords\":[\"El TDA frente al TDAH: \u00bfCu\u00e1l es la diferencia?\",\"S\u00edntomas del TDA\"],\"articleSection\":[\"TDAH\"],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.diagnostico-mente.org\/blog\/#\/schema\/person\/8eb1bcaf59fea75c780c11946f4e3490\",\"name\":\"Diagn\u00f3stico Mente\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.diagnostico-mente.org\/blog\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/db47a00a472ca08e0cb5053901a4e9b1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/db47a00a472ca08e0cb5053901a4e9b1?s=96&d=mm&r=g\",\"caption\":\"Diagn\u00f3stico Mente\"},\"sameAs\":[\"https:\/\/www.diagnostico-mente.org\/blog\"],\"url\":\"https:\/\/www.diagnostico-mente.org\/blog\/author\/diagnostyka-umyslu\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TDA y TDAH: Diferencias, diagn\u00f3stico y tratamiento - Diagn\u00f3stico Mente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/tda-y-tdah-diferencias-diagnostico-y-tratamiento\/","og_locale":"es_ES","og_type":"article","og_title":"TDA y TDAH: Diferencias, diagn\u00f3stico y tratamiento - Diagn\u00f3stico Mente","og_description":"El trastorno por d\u00e9ficit de atenci\u00f3n (TDA) es un t\u00e9rmino que a veces se utiliza para referirse a una forma de trastorno por d\u00e9ficit de...","og_url":"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/tda-y-tdah-diferencias-diagnostico-y-tratamiento\/","og_site_name":"Diagn\u00f3stico Mente","article_published_time":"2022-08-01T06:00:03+00:00","article_modified_time":"2022-07-11T18:37:36+00:00","og_image":[{"width":840,"height":202,"url":"https:\/\/www.diagnostico-mente.org\/blog\/wp-content\/uploads\/2022\/07\/bg_top_default-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Diagn\u00f3stico Mente","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/www.diagnostico-mente.org\/blog\/#organization","name":"Diagn\u00f3stico Mente","url":"https:\/\/www.diagnostico-mente.org\/blog\/","sameAs":[],"logo":{"@type":"ImageObject","@id":"https:\/\/www.diagnostico-mente.org\/blog\/#logo","inLanguage":"es","url":"https:\/\/www.diagnostico-mente.org\/blog\/wp-content\/uploads\/2022\/06\/logo_blog.png","contentUrl":"https:\/\/www.diagnostico-mente.org\/blog\/wp-content\/uploads\/2022\/06\/logo_blog.png","width":252,"height":75,"caption":"Diagn\u00f3stico Mente"},"image":{"@id":"https:\/\/www.diagnostico-mente.org\/blog\/#logo"}},{"@type":"WebSite","@id":"https:\/\/www.diagnostico-mente.org\/blog\/#website","url":"https:\/\/www.diagnostico-mente.org\/blog\/","name":"Diagn\u00f3stico Mente","description":"Blog sobre los trastornos de la mente","publisher":{"@id":"https:\/\/www.diagnostico-mente.org\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.diagnostico-mente.org\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/tda-y-tdah-diferencias-diagnostico-y-tratamiento\/#primaryimage","inLanguage":"es","url":"https:\/\/www.diagnostico-mente.org\/blog\/wp-content\/uploads\/2022\/07\/bg_top_default-1.jpg","contentUrl":"https:\/\/www.diagnostico-mente.org\/blog\/wp-content\/uploads\/2022\/07\/bg_top_default-1.jpg","width":840,"height":202},{"@type":"WebPage","@id":"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/tda-y-tdah-diferencias-diagnostico-y-tratamiento\/#webpage","url":"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/tda-y-tdah-diferencias-diagnostico-y-tratamiento\/","name":"TDA y TDAH: Diferencias, diagn\u00f3stico y tratamiento - Diagn\u00f3stico Mente","isPartOf":{"@id":"https:\/\/www.diagnostico-mente.org\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/tda-y-tdah-diferencias-diagnostico-y-tratamiento\/#primaryimage"},"datePublished":"2022-08-01T06:00:03+00:00","dateModified":"2022-07-11T18:37:36+00:00","breadcrumb":{"@id":"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/tda-y-tdah-diferencias-diagnostico-y-tratamiento\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.diagnostico-mente.org\/blog\/tdah\/tda-y-tdah-diferencias-diagnostico-y-tratamiento\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/tda-y-tdah-diferencias-diagnostico-y-tratamiento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"P\u00e1gina","item":"https:\/\/www.diagnostico-mente.org\/blog\/"},{"@type":"ListItem","position":2,"name":"TDAH","item":"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/"},{"@type":"ListItem","position":3,"name":"TDA y TDAH: Diferencias, diagn\u00f3stico y tratamiento"}]},{"@type":"Article","@id":"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/tda-y-tdah-diferencias-diagnostico-y-tratamiento\/#article","isPartOf":{"@id":"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/tda-y-tdah-diferencias-diagnostico-y-tratamiento\/#webpage"},"author":{"@id":"https:\/\/www.diagnostico-mente.org\/blog\/#\/schema\/person\/8eb1bcaf59fea75c780c11946f4e3490"},"headline":"TDA y TDAH: Diferencias, diagn\u00f3stico y tratamiento","datePublished":"2022-08-01T06:00:03+00:00","dateModified":"2022-07-11T18:37:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/tda-y-tdah-diferencias-diagnostico-y-tratamiento\/#webpage"},"wordCount":1626,"publisher":{"@id":"https:\/\/www.diagnostico-mente.org\/blog\/#organization"},"image":{"@id":"https:\/\/www.diagnostico-mente.org\/blog\/tdah\/tda-y-tdah-diferencias-diagnostico-y-tratamiento\/#primaryimage"},"thumbnailUrl":"https:\/\/www.diagnostico-mente.org\/blog\/wp-content\/uploads\/2022\/07\/bg_top_default-1.jpg","keywords":["El TDA frente al TDAH: \u00bfCu\u00e1l es la diferencia?","S\u00edntomas del TDA"],"articleSection":["TDAH"],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.diagnostico-mente.org\/blog\/#\/schema\/person\/8eb1bcaf59fea75c780c11946f4e3490","name":"Diagn\u00f3stico Mente","image":{"@type":"ImageObject","@id":"https:\/\/www.diagnostico-mente.org\/blog\/#personlogo","inLanguage":"es","url":"https:\/\/secure.gravatar.com\/avatar\/db47a00a472ca08e0cb5053901a4e9b1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/db47a00a472ca08e0cb5053901a4e9b1?s=96&d=mm&r=g","caption":"Diagn\u00f3stico Mente"},"sameAs":["https:\/\/www.diagnostico-mente.org\/blog"],"url":"https:\/\/www.diagnostico-mente.org\/blog\/author\/diagnostyka-umyslu\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.diagnostico-mente.org\/blog\/wp-json\/wp\/v2\/posts\/1918"}],"collection":[{"href":"https:\/\/www.diagnostico-mente.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diagnostico-mente.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diagnostico-mente.org\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diagnostico-mente.org\/blog\/wp-json\/wp\/v2\/comments?post=1918"}],"version-history":[{"count":1,"href":"https:\/\/www.diagnostico-mente.org\/blog\/wp-json\/wp\/v2\/posts\/1918\/revisions"}],"predecessor-version":[{"id":1920,"href":"https:\/\/www.diagnostico-mente.org\/blog\/wp-json\/wp\/v2\/posts\/1918\/revisions\/1920"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diagnostico-mente.org\/blog\/wp-json\/wp\/v2\/media\/1718"}],"wp:attachment":[{"href":"https:\/\/www.diagnostico-mente.org\/blog\/wp-json\/wp\/v2\/media?parent=1918"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diagnostico-mente.org\/blog\/wp-json\/wp\/v2\/categories?post=1918"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diagnostico-mente.org\/blog\/wp-json\/wp\/v2\/tags?post=1918"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}